{"id":41,"date":"2018-11-21T04:37:32","date_gmt":"2018-11-21T04:37:32","guid":{"rendered":"http:\/\/localhost\/St.%20ThereseSchool\/?p=41"},"modified":"2026-06-10T03:07:51","modified_gmt":"2026-06-10T03:07:51","slug":"inauguration","status":"publish","type":"post","link":"https:\/\/stthereseschoolchalakudy.com\/index.php\/2018\/11\/21\/inauguration\/","title":{"rendered":"Infrastructure"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":498,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/posts\/41"}],"collection":[{"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/comments?post=41"}],"version-history":[{"count":2,"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/posts\/41\/revisions"}],"predecessor-version":[{"id":499,"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/posts\/41\/revisions\/499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/media\/498"}],"wp:attachment":[{"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/media?parent=41"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/categories?post=41"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/tags?post=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}