{"id":70,"date":"2018-11-21T08:20:31","date_gmt":"2018-11-21T08:20:31","guid":{"rendered":"http:\/\/stthereseschoolchalakudy.com\/?page_id=70"},"modified":"2018-11-21T10:04:23","modified_gmt":"2018-11-21T10:04:23","slug":"infrastructure","status":"publish","type":"page","link":"https:\/\/stthereseschoolchalakudy.com\/index.php\/infrastructure\/","title":{"rendered":"INFRASTRUCTURE"},"content":{"rendered":"<p><img loading=\"lazy\" src=\"http:\/\/stthereseschoolchalakudy.com\/wp-content\/uploads\/2018\/11\/INFRASTRUCTURE.jpg\" alt=\"\" width=\"240\" height=\"143\" class=\"alignnone size-full wp-image-95\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/pages\/70"}],"collection":[{"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/comments?post=70"}],"version-history":[{"count":2,"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/pages\/70\/revisions"}],"predecessor-version":[{"id":96,"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/pages\/70\/revisions\/96"}],"wp:attachment":[{"href":"https:\/\/stthereseschoolchalakudy.com\/index.php\/wp-json\/wp\/v2\/media?parent=70"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}